{"id":950,"date":"2020-01-26T06:20:54","date_gmt":"2020-01-26T06:20:54","guid":{"rendered":"https:\/\/juristic.themegeniuslab.com\/?page_id=18"},"modified":"2026-03-16T15:31:55","modified_gmt":"2026-03-16T14:31:55","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/advsmiljanamedic.rs\/en\/kontakt\/","title":{"rendered":"Contact"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"950\" class=\"elementor elementor-950\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9080a27 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9080a27\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24c05e9\" data-id=\"24c05e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaf4633 elementor-widget elementor-widget-image\" data-id=\"aaf4633\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"350\" src=\"https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/header2.webp\" class=\"attachment-full size-full wp-image-2095\" alt=\"\" srcset=\"https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/header2.webp 1920w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/header2-300x55.webp 300w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/header2-1024x187.webp 1024w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/header2-768x140.webp 768w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/header2-1536x280.webp 1536w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/header2-18x3.webp 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1daecb1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1daecb1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b066461\" data-id=\"b066461\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36f3473 elementor-widget__width-initial elementor-widget elementor-widget-tmx-juristic_contactinfo\" data-id=\"36f3473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tmx-juristic_contactinfo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"juristic-contact-section contact-section-s3\">\n\t\t\t<div class=\"content-area clearfix\">\n\n\t\t\t\t<div class=\"contact-info-col\">\n\t\t\t\t\t<div class=\"contact-info\">\n\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fi flaticon-home-3\"><\/i><h4>Address<\/h4><p>Matije Korvina 17, Hotel Galleria 1.sprat, Subotica<\/p>\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fi flaticon-email\"><\/i><h4>E-mail<\/h4><p>advokat.smiljana.medic@gmail.com<\/p>\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fi flaticon-support\"><\/i><h4>Phone<\/h4><p>+381631035379<\/p>\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fi flaticon-clock\"><\/i><h4>Working time<\/h4><p>Monday-Friday: 8am-4pm<\/p>\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"contact-form-col\">\n\t\t\t\t\t<div class=\"section-title-s2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t\t\t\t<i class=\"fi fi flaticon-home-3\"><\/i>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<span>Contact us<\/span><h2>Lawyer Smiljana Medi\u0107<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"contact-form\">\n\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f226-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"226\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/950#wpcf7-f226-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/950#wpcf7-f226-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"226\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f226-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-29\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"text-29\" \/><\/span>\n\t<\/p>\n<\/div>\n<div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email-75\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"email-75\" \/><\/span>\n\t<\/p>\n<\/div>\n<div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-806\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"text\" name=\"text-806\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"fullwidth\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-225\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Text\" name=\"textarea-225\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<div class=\"submit-area\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner theme-btn-s3\" type=\"submit\" value=\"Send\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div> <!-- end content-area -->\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9346602 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9346602\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7af7bfb\" data-id=\"7af7bfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddec206 elementor-widget elementor-widget-google_maps\" data-id=\"ddec206\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Matije%20Korvina%2017%2C%20Subotica&#038;t=m&#038;z=17&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Matije Korvina 17, Subotica\"\n\t\t\t\t\taria-label=\"Matije Korvina 17, Subotica\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48b16b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48b16b3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-679b03e\" data-id=\"679b03e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97d1952 elementor-widget elementor-widget-image\" data-id=\"97d1952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/advsmiljanamedic.rs\/en\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/3-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-1205\" alt=\"\" srcset=\"https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/3-150x150.png 150w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/3-300x300.png 300w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/3-768x768.png 768w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/3-600x600.png 600w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/3-100x100.png 100w, https:\/\/advsmiljanamedic.rs\/wp-content\/uploads\/2025\/03\/3.png 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"Adresa Matije Korvina 17, Hotel Galleria 1.sprat, Subotica E-mail advokat.smiljana.medic@gmail.com Telefon +381631035379 Radno vreme Ponedeljak-Petak: 8:00-16:00 Kontaktirajte nas Advokat Smiljana Medi\u0107","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-950","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/advsmiljanamedic.rs\/en\/wp-json\/wp\/v2\/pages\/950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advsmiljanamedic.rs\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/advsmiljanamedic.rs\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/advsmiljanamedic.rs\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/advsmiljanamedic.rs\/en\/wp-json\/wp\/v2\/comments?post=950"}],"version-history":[{"count":114,"href":"https:\/\/advsmiljanamedic.rs\/en\/wp-json\/wp\/v2\/pages\/950\/revisions"}],"predecessor-version":[{"id":2400,"href":"https:\/\/advsmiljanamedic.rs\/en\/wp-json\/wp\/v2\/pages\/950\/revisions\/2400"}],"wp:attachment":[{"href":"https:\/\/advsmiljanamedic.rs\/en\/wp-json\/wp\/v2\/media?parent=950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}